{"id":3446,"date":"2024-06-23T13:26:07","date_gmt":"2024-06-23T13:26:07","guid":{"rendered":"https:\/\/smartgatefactory.com\/product\/%d8%ad%d9%82%d9%8a%d8%a8%d8%a9-%d9%84%d8%aa%d8%a7%d8%a8%d9%84%d8%aa-10-%d8%a8%d9%88%d8%b5%d9%87-%d9%85%d8%b9-%d8%ad%d8%b2%d8%a7%d9%85-%d9%83%d8%aa%d9%81-%d9%85%d9%86-%d8%b3%d9%85%d8%a7%d8%b1%d8%aa-6\/"},"modified":"2025-02-02T12:14:49","modified_gmt":"2025-02-02T12:14:49","slug":"%d8%ad%d9%82%d9%8a%d8%a8%d8%a9-%d9%84%d8%aa%d8%a7%d8%a8%d9%84%d8%aa-10-%d8%a8%d9%88%d8%b5%d9%87-%d9%85%d8%b9-%d8%ad%d8%b2%d8%a7%d9%85-%d9%83%d8%aa%d9%81-%d9%85%d9%86-%d8%b3%d9%85%d8%a7%d8%b1%d8%aa-6","status":"publish","type":"product","link":"https:\/\/smartgatefactory.com\/ar\/product\/%d8%ad%d9%82%d9%8a%d8%a8%d8%a9-%d9%84%d8%aa%d8%a7%d8%a8%d9%84%d8%aa-10-%d8%a8%d9%88%d8%b5%d9%87-%d9%85%d8%b9-%d8%ad%d8%b2%d8%a7%d9%85-%d9%83%d8%aa%d9%81-%d9%85%d9%86-%d8%b3%d9%85%d8%a7%d8%b1%d8%aa-6\/","title":{"rendered":"\u062d\u0642\u064a\u0628\u0629 \u0644\u062a\u0627\u0628\u0644\u062a 10 \u0628\u0648\u0635\u0647 \u0645\u0639 \u062d\u0632\u0627\u0645 \u0643\u062a\u0641 \u0645\u0646 \u0633\u0645\u0627\u0631\u062a \u062c\u064a\u062a \u0628\u064a\u062c"},"content":{"rendered":"<div class=\"presented-response-container ng-tns-c1044028905-124\">\n<div class=\"response-container-content ng-tns-c1044028905-124 tunable-selection-with-avatar\">\n<div class=\"response-content ng-tns-c1044028905-124\">\n<div class=\"markdown markdown-main-panel\" dir=\"rtl\">\n<p data-sourcepos=\"3:1-3:15\"><span style=\"font-size: 14pt;\">\u062e\u0627\u0645\u0629 \u0627\u0644\u0635\u0646\u0639:<\/span><\/p>\n<ul data-sourcepos=\"5:1-6:0\">\n<li data-sourcepos=\"5:1-6:0\"><span style=\"font-size: 14pt;\">\u062c\u0644\u062f \u0635\u0646\u0627\u0639\u064a \u0645\u0642\u0627\u0648\u0645 \u0644\u0644\u0645\u0627\u0621<\/span><\/li>\n<\/ul>\n<p data-sourcepos=\"7:1-7:11\"><span style=\"font-size: 14pt;\">\u0627\u0644\u062c\u064a\u0648\u0628:<\/span><\/p>\n<ul data-sourcepos=\"9:1-12:0\">\n<li data-sourcepos=\"9:1-9:16\"><span style=\"font-size: 14pt;\">\u062c\u064a\u0648\u0628 \u0623\u0633\u0627\u0633\u064a\u0629: 3<\/span><\/li>\n<li data-sourcepos=\"10:1-10:16\"><span style=\"font-size: 14pt;\">\u062c\u064a\u0648\u0628 \u062b\u0627\u0646\u0648\u064a\u0629: 1<\/span><\/li>\n<li data-sourcepos=\"11:1-12:0\"><span style=\"font-size: 14pt;\">\u062c\u064a\u0648\u0628 \u062c\u0627\u0646\u0628\u064a\u0629: \u0644\u0627 \u064a\u0648\u062c\u062f<\/span><\/li>\n<\/ul>\n<p data-sourcepos=\"13:1-13:12\"><span style=\"font-size: 14pt;\">\u0627\u0644\u0623\u0628\u0639\u0627\u062f:<\/span><\/p>\n<ul data-sourcepos=\"15:1-16:0\">\n<li data-sourcepos=\"15:1-16:0\"><span style=\"font-size: 14pt;\">7 \u00d7 21 \u00d7 25 \u0633\u0645<\/span><\/li>\n<\/ul>\n<p data-sourcepos=\"17:1-17:10\"><span style=\"font-size: 14pt;\">\u0627\u0644\u0648\u0632\u0646:<\/span><\/p>\n<ul data-sourcepos=\"19:1-19:10\">\n<li data-sourcepos=\"19:1-19:10\"><span style=\"font-size: 14pt;\">0.30 \u0643\u062c\u0645<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"response-container-footer ng-tns-c1044028905-124\">\n<div class=\"actions-container-v2 ng-star-inserted\">\n<div class=\"buttons-container-v2 ng-star-inserted\"><\/div>\n<\/div>\n<\/div>\n<p dir=\"rtl\"><span style=\"font-size: 14pt;\">\u0627\u0644\u0645\u0645\u064a\u0632\u0627\u062a<\/span><\/p>\n<ul dir=\"rtl\">\n<li><span style=\"font-size: 14pt;\">\u062e\u0627\u0645\u0627\u062a \u0645\u062a\u064a\u0646\u0629 \u0648\u0645\u0642\u0627\u0648\u0645\u0629 \u0644\u0644\u0645\u0627\u0621 \u0645\u0646 \u0627\u0644\u062c\u0644\u062f \u0627\u0644\u0635\u0646\u0627\u0639\u0649<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">\u062a\u062a\u0645\u064a\u0632 \u0628\u062e\u0627\u0645\u0627\u062a \u062f\u0627\u062e\u0644\u064a\u0629 \u0623\u0645\u0646\u0629 \u0644\u0644\u0645\u0644\u062d\u0642\u0627\u062a \u0627\u0644\u0635\u063a\u064a\u0631\u0629.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">\u0628\u0647\u0627 \u062d\u0632\u0627\u0645 \u0637\u0648\u064a\u0644 \u0644\u0627\u0631\u062a\u062f\u0627\u0621\u0647\u0627 \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u0633\u0641\u0631 \u0648\u0627\u0644\u062a\u062c\u0648\u0627\u0644 \u0643\u0645\u0627 \u0623\u0646\u0647 \u064a\u0648\u062c\u062f \u0628\u0647\u0627 \u0645\u0642\u0628\u0636 \u0631\u0623\u0633\u064a \u0646\u0627\u0639\u0645 \u0644\u0633\u0647\u0648\u0644\u0629 \u062d\u0645\u0644\u0647\u0627 \u0628\u064a\u062f\u0643.<\/span><\/li>\n<\/ul>\n<p dir=\"rtl\"><span style=\"font-size: 14pt;\">\u0627\u0644\u0623\u0644\u0648\u0627\u0646<\/span><\/p>\n<ul dir=\"rtl\">\n<li><span style=\"font-size: 14pt;\">\u0623\u0633\u0648\u062f\/\u062c\u0645\u0644\u0649<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<ul dir=\"rtl\">\n<li><span style=\"font-size: 14pt;\">\u062e\u0627\u0645\u0627\u062a \u0645\u062a\u064a\u0646\u0629 \u0648\u0645\u0642\u0627\u0648\u0645\u0629 \u0644\u0644\u0645\u0627\u0621 \u0645\u0646 \u0627\u0644\u062c\u0644\u062f \u0627\u0644\u0635\u0646\u0627\u0639\u0649<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">\u062a\u062a\u0645\u064a\u0632 \u0628\u062e\u0627\u0645\u0627\u062a \u062f\u0627\u062e\u0644\u064a\u0629 \u0623\u0645\u0646\u0629 \u0644\u0644\u0645\u0644\u062d\u0642\u0627\u062a \u0627\u0644\u0635\u063a\u064a\u0631\u0629.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">\u0628\u0647\u0627 \u062d\u0632\u0627\u0645 \u0637\u0648\u064a\u0644 \u0644\u0627\u0631\u062a\u062f\u0627\u0621\u0647\u0627 \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u0633\u0641\u0631 \u0648\u0627\u0644\u062a\u062c\u0648\u0627\u0644 \u0643\u0645\u0627 \u0623\u0646\u0647 \u064a\u0648\u062c\u062f \u0628\u0647\u0627 \u0645\u0642\u0628\u0636 \u0631\u0623\u0633\u064a \u0646\u0627\u0639\u0645 \u0644\u0633\u0647\u0648\u0644\u0629 \u062d\u0645\u0644\u0647\u0627 \u0628\u064a\u062f\u0643.<\/span><\/li>\n<\/ul>\n<p dir=\"rtl\">622883739036<\/p>\n","protected":false},"featured_media":3030,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_brand":[],"product_cat":[129,60],"product_tag":[],"class_list":["post-3446","product","type-product","status-publish","has-post-thumbnail","product_cat-bags","product_cat-carry-case","pa_color-black-camel","first","instock","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/product\/3446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/comments?post=3446"}],"version-history":[{"count":6,"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/product\/3446\/revisions"}],"predecessor-version":[{"id":5990,"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/product\/3446\/revisions\/5990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/media\/3030"}],"wp:attachment":[{"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/media?parent=3446"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/product_brand?post=3446"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/product_cat?post=3446"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/smartgatefactory.com\/ar\/wp-json\/wp\/v2\/product_tag?post=3446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}